{"id":1404,"date":"2024-05-13T09:42:41","date_gmt":"2024-05-13T09:42:41","guid":{"rendered":"https:\/\/www.beauvoordsbakhuis.be\/2024\/05\/13\/crepes-salees-au-jambon-et-fromage\/"},"modified":"2024-06-04T08:11:24","modified_gmt":"2024-06-04T08:11:24","slug":"crepes-salees-au-jambon-et-fromage","status":"publish","type":"post","link":"https:\/\/www.beauvoordsbakhuis.be\/fr\/2024\/05\/13\/crepes-salees-au-jambon-et-fromage\/","title":{"rendered":"Cr\u00eapes sal\u00e9es au jambon et fromage"},"content":{"rendered":"\n<p><\/p>\n\n<p>Ingr\u00e9dients : <\/p>\n\n<ul class=\"wp-block-list\">\n<li>400 grammes de fromage r\u00e2p\u00e9 (type Emmental, Gruy\u00e8re ou Comte)<\/li>\n\n\n\n<li>400 grammes de jambon cuit<\/li>\n\n\n\n<li>9 cr\u00eapes naturel de Beauvoords Bakhuis <\/li>\n\n\n\n<li>Poivre ou paprika fum\u00e9<\/li>\n\n\n\n<li>Beurre<\/li>\n\n\n\n<li>Salade mixte<\/li>\n\n\n\n<li>Vinaigre de pomme<\/li>\n<\/ul>\n\n<p><\/p>\n\n<p>Pr\u00e9paration<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Faire fondre une noix de beurre dans la po\u00eale.<\/li>\n\n\n\n<li>D\u00e9poser une cr\u00eape dans la po\u00eale, saupoudrer la moiti\u00e9 de fromage moulu et recouvrir d&rsquo;une tranche de jambon. <\/li>\n\n\n\n<li>Assaisonner \u00e9ventuellement d&rsquo;un peu de poivre ou de paprika.<\/li>\n\n\n\n<li>Refermer la cr\u00eape et la retourner d\u00e8s que le fromage est fondu. Faire frire l&rsquo;autre face \u00e9galement. <\/li>\n\n\n\n<li>M\u00e9langer la laitue avec un peu d&rsquo;huile d&rsquo;olive et de vinaigre de cidre de pomme.<\/li>\n\n\n\n<li>Servir ensemble.<\/li>\n<\/ul>\n\n<p><\/p>\n\n<p>Bon app\u00e9tit !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingr\u00e9dients : Pr\u00e9paration Bon app\u00e9tit !<\/p>\n","protected":false},"author":2,"featured_media":1281,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recettes"],"_links":{"self":[{"href":"https:\/\/www.beauvoordsbakhuis.be\/fr\/wp-json\/wp\/v2\/posts\/1404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.beauvoordsbakhuis.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.beauvoordsbakhuis.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.beauvoordsbakhuis.be\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.beauvoordsbakhuis.be\/fr\/wp-json\/wp\/v2\/comments?post=1404"}],"version-history":[{"count":1,"href":"https:\/\/www.beauvoordsbakhuis.be\/fr\/wp-json\/wp\/v2\/posts\/1404\/revisions"}],"predecessor-version":[{"id":1405,"href":"https:\/\/www.beauvoordsbakhuis.be\/fr\/wp-json\/wp\/v2\/posts\/1404\/revisions\/1405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.beauvoordsbakhuis.be\/fr\/wp-json\/wp\/v2\/media\/1281"}],"wp:attachment":[{"href":"https:\/\/www.beauvoordsbakhuis.be\/fr\/wp-json\/wp\/v2\/media?parent=1404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.beauvoordsbakhuis.be\/fr\/wp-json\/wp\/v2\/categories?post=1404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.beauvoordsbakhuis.be\/fr\/wp-json\/wp\/v2\/tags?post=1404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}